{"id":51,"count":0,"description":"","link":"https:\/\/hotelmoscow.net\/ec\/product-category\/fashion\/","name":"Fashion","slug":"fashion","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/product_cat\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/product?product_cat=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}