{"id":26,"count":2,"description":"","link":"https:\/\/hotelmoscow.net\/ec\/category\/traveling\/","name":"Traveling","slug":"traveling","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hotelmoscow.net\/ec\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}